{"id":353,"date":"2018-10-19T11:47:36","date_gmt":"2018-10-19T09:47:36","guid":{"rendered":"https:\/\/aufstellungsrituale.de\/?page_id=353"},"modified":"2025-11-12T16:32:52","modified_gmt":"2025-11-12T15:32:52","slug":"newsletter","status":"publish","type":"page","link":"https:\/\/aufstellungsrituale.de\/en\/newsletter\/","title":{"rendered":"(Deutsch) Newsletter"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-en\">Sorry, this entry is only available in <a href=\"https:\/\/aufstellungsrituale.de\/de\/wp-json\/wp\/v2\/pages\/353\" class=\"qtranxs-available-language-link qtranxs-available-language-link-de\" title=\"Deutsch\">Deutsch<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sorry, this entry is only available in Deutsch.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-353","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/aufstellungsrituale.de\/newsletter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals\" \/>\n<meta property=\"og:description\" content=\"Sorry, this entry is only available in Deutsch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aufstellungsrituale.de\/newsletter\/\" \/>\n<meta property=\"og:site_name\" content=\"Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-12T15:32:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/newsletter\\\/\",\"url\":\"https:\\\/\\\/aufstellungsrituale.de\\\/newsletter\\\/\",\"name\":\"(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#website\"},\"datePublished\":\"2018-10-19T09:47:36+00:00\",\"dateModified\":\"2025-11-12T15:32:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/newsletter\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aufstellungsrituale.de\\\/newsletter\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/newsletter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/aufstellungsrituale.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newsletter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#website\",\"url\":\"https:\\\/\\\/aufstellungsrituale.de\\\/\",\"name\":\"Aufstellungsarbeit in Verbindung mit Schamanischer Ritualarbeit\",\"description\":\"finden was wirkt\",\"publisher\":{\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aufstellungsrituale.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#organization\",\"name\":\"Kreative Beratung - Cornelia Nicola\",\"url\":\"https:\\\/\\\/aufstellungsrituale.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/aufstellungsrituale.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo.gif\",\"contentUrl\":\"https:\\\/\\\/aufstellungsrituale.de\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/logo.gif\",\"width\":195,\"height\":93,\"caption\":\"Kreative Beratung - Cornelia Nicola\"},\"image\":{\"@id\":\"https:\\\/\\\/aufstellungsrituale.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/aufstellungsrituale.de\/newsletter\/","og_locale":"en_US","og_type":"article","og_title":"(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals","og_description":"Sorry, this entry is only available in Deutsch.","og_url":"https:\/\/aufstellungsrituale.de\/newsletter\/","og_site_name":"Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals","article_modified_time":"2025-11-12T15:32:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/aufstellungsrituale.de\/newsletter\/","url":"https:\/\/aufstellungsrituale.de\/newsletter\/","name":"(Deutsch) Newsletter - Constellation-Rituals Shaman Ritual work in Combination with systemic Shamanic Constellation-Rituals","isPartOf":{"@id":"https:\/\/aufstellungsrituale.de\/#website"},"datePublished":"2018-10-19T09:47:36+00:00","dateModified":"2025-11-12T15:32:52+00:00","breadcrumb":{"@id":"https:\/\/aufstellungsrituale.de\/newsletter\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aufstellungsrituale.de\/newsletter\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/aufstellungsrituale.de\/newsletter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/aufstellungsrituale.de\/"},{"@type":"ListItem","position":2,"name":"Newsletter"}]},{"@type":"WebSite","@id":"https:\/\/aufstellungsrituale.de\/#website","url":"https:\/\/aufstellungsrituale.de\/","name":"Aufstellungsarbeit in Verbindung mit Schamanischer Ritualarbeit","description":"finden was wirkt","publisher":{"@id":"https:\/\/aufstellungsrituale.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aufstellungsrituale.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/aufstellungsrituale.de\/#organization","name":"Kreative Beratung - Cornelia Nicola","url":"https:\/\/aufstellungsrituale.de\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/aufstellungsrituale.de\/#\/schema\/logo\/image\/","url":"https:\/\/aufstellungsrituale.de\/wp-content\/uploads\/2019\/02\/logo.gif","contentUrl":"https:\/\/aufstellungsrituale.de\/wp-content\/uploads\/2019\/02\/logo.gif","width":195,"height":93,"caption":"Kreative Beratung - Cornelia Nicola"},"image":{"@id":"https:\/\/aufstellungsrituale.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/pages\/353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/comments?post=353"}],"version-history":[{"count":27,"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/pages\/353\/revisions"}],"predecessor-version":[{"id":3404,"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/pages\/353\/revisions\/3404"}],"wp:attachment":[{"href":"https:\/\/aufstellungsrituale.de\/en\/wp-json\/wp\/v2\/media?parent=353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}